{"id":157,"count":2,"description":"","link":"https:\/\/analyticsmart.com\/fr\/category\/ai-in-retail\/","name":"AI In Retail","slug":"ai-in-retail","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>AI In Retail Archives - Analyticsmart<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/analyticsmart.com\/fr\/category\/ai-in-retail\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"AI In Retail Archives - Analyticsmart\" \/>\n<meta property=\"og:url\" content=\"https:\/\/analyticsmart.com\/fr\/category\/ai-in-retail\/\" \/>\n<meta property=\"og:site_name\" content=\"Analyticsmart\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/analyticsmart.com\\\/category\\\/ai-in-retail\\\/\",\"url\":\"https:\\\/\\\/analyticsmart.com\\\/category\\\/ai-in-retail\\\/\",\"name\":\"AI In Retail Archives - Analyticsmart\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/analyticsmart.com\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/analyticsmart.com\\\/category\\\/ai-in-retail\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/analyticsmart.com\\\/category\\\/ai-in-retail\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/analyticsmart.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"AI In Retail\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/analyticsmart.com\\\/#website\",\"url\":\"https:\\\/\\\/analyticsmart.com\\\/\",\"name\":\"Analyticsmart\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/analyticsmart.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"AI In Retail Archives - Analyticsmart","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/analyticsmart.com\/fr\/category\/ai-in-retail\/","og_locale":"fr_FR","og_type":"article","og_title":"AI In Retail Archives - Analyticsmart","og_url":"https:\/\/analyticsmart.com\/fr\/category\/ai-in-retail\/","og_site_name":"Analyticsmart","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/analyticsmart.com\/category\/ai-in-retail\/","url":"https:\/\/analyticsmart.com\/category\/ai-in-retail\/","name":"AI In Retail Archives - Analyticsmart","isPartOf":{"@id":"https:\/\/analyticsmart.com\/#website"},"breadcrumb":{"@id":"https:\/\/analyticsmart.com\/category\/ai-in-retail\/#breadcrumb"},"inLanguage":"fr-FR"},{"@type":"BreadcrumbList","@id":"https:\/\/analyticsmart.com\/category\/ai-in-retail\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/analyticsmart.com\/"},{"@type":"ListItem","position":2,"name":"AI In Retail"}]},{"@type":"WebSite","@id":"https:\/\/analyticsmart.com\/#website","url":"https:\/\/analyticsmart.com\/","name":"Analyticsmart","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/analyticsmart.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"_links":{"self":[{"href":"https:\/\/analyticsmart.com\/fr\/wp-json\/wp\/v2\/categories\/157","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/analyticsmart.com\/fr\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/analyticsmart.com\/fr\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/analyticsmart.com\/fr\/wp-json\/wp\/v2\/posts?categories=157"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}